{"id":10656,"date":"2011-06-03T02:44:04","date_gmt":"2011-06-03T02:44:04","guid":{"rendered":"http:\/\/www.portugalvia.com\/?p=10656"},"modified":"2012-04-14T03:55:36","modified_gmt":"2012-04-14T03:55:36","slug":"parque-de-campismo-da-quinta-das-cegonhas","status":"publish","type":"post","link":"https:\/\/portugalvia.com\/vp\/parque-de-campismo-da-quinta-das-cegonhas\/","title":{"rendered":"Parque de Campismo da Quinta das Cegonhas"},"content":{"rendered":"<p><a href=\"http:\/\/www.portugalvia.com\/vp\/wp-content\/uploads\/2011\/06\/quinta-das-cegonhas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-11464\" title=\"quinta das cegonhas\" src=\"http:\/\/www.portugalvia.com\/vp\/wp-content\/uploads\/2011\/06\/quinta-das-cegonhas-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/portugalvia.com\/vp\/wp-content\/uploads\/2011\/06\/quinta-das-cegonhas-300x187.jpg 300w, https:\/\/portugalvia.com\/vp\/wp-content\/uploads\/2011\/06\/quinta-das-cegonhas.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>O Parque de Campismo da Quinta das Cegonhas situa-se na Quinta das Cegonhas, no concelho de Gouveia, em pleno Parque Natural da Serra da Estrela, numa rela\u00e7\u00e3o privilegiada de contacto com a natureza.<\/p>\n<p>A sua estrutura \u00e9 constitu\u00edda por patamares relvados, delimitados por arbustos naturais, que proporcionam uma bela vista panor\u00e2mica. O cen\u00e1rio natural, \u00e9 completado por \u00e1rvores de fruto e de esp\u00e9cies diversas.<\/p>\n<p>O Parque disp\u00f5e de aluguer de caravanas, anima\u00e7\u00e3o, bar, alv\u00e9olos, parque infantil, piscina, restaurante, sala de conv\u00edvio, piscina, snack-bar, sombra m\u00e9dia, t\u00e9nis de mesa e tomadas de corrente para tendas e caravanas.<\/p>\n<p>Ao redor da Quinta, pode-se explorar os percursos pedestres existentes. A 300 metros, existe uma esta\u00e7\u00e3o de autocarros, a 1 quil\u00f3metro, existe uma esta\u00e7\u00e3o de correios, \u00a0pesca a 8 quil\u00f3metros e \u00a0a 11 quil\u00f3metros, uma esta\u00e7\u00e3o de comboios.<\/p>\n<p>Na Serra da Estrela, existem v\u00e1rias actividades que se podem realizar, especialmente desportos de inverno. Nas proximidades, encontram-se algumas aldeias hist\u00f3ricas, locais de grande interesse tur\u00edstico.<\/p>\n<p><strong>Quinta das Cegonhas<br \/>\n6290 &#8211; 122 Gouveia<br \/>\nNaba\u00ednhos<br \/>\nPortugal<br \/>\nTelefone- (00351) 238 745 886<\/strong><\/p>\n<p><a href=\"http:\/\/www.cegonhas.com\/\"><span style=\"color: #008080;\">http:\/\/www.cegonhas.com\/<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Parque de Campismo da Quinta das Cegonhas situa-se na Quinta das Cegonhas, no concelho de Gouveia, em pleno Parque Natural da Serra da Estrela, numa rela\u00e7\u00e3o privilegiada de contacto com a natureza. A sua estrutura \u00e9 constitu\u00edda por patamares relvados, delimitados por arbustos naturais, que proporcionam uma bela vista panor\u00e2mica. O cen\u00e1rio natural, \u00e9 completado por \u00e1rvores de fruto e de esp\u00e9cies diversas. O Parque disp\u00f5e de aluguer de caravanas, anima\u00e7\u00e3o, bar, alv\u00e9olos, parque [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,84],"tags":[],"class_list":["post-10656","post","type-post","status-publish","format-standard","hentry","category-guarda","category-parques-de-campismo-guarda"],"_links":{"self":[{"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/posts\/10656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/comments?post=10656"}],"version-history":[{"count":6,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/posts\/10656\/revisions"}],"predecessor-version":[{"id":13152,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/posts\/10656\/revisions\/13152"}],"wp:attachment":[{"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/media?parent=10656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/categories?post=10656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/tags?post=10656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}