{"id":17464,"date":"2012-01-12T05:36:47","date_gmt":"2012-01-12T05:36:47","guid":{"rendered":"http:\/\/www.portugalvia.com\/?p=17464"},"modified":"2012-01-19T17:14:40","modified_gmt":"2012-01-19T17:14:40","slug":"antilia-hotel-apartamento","status":"publish","type":"post","link":"https:\/\/portugalvia.com\/vp\/antilia-hotel-apartamento\/","title":{"rendered":"Antilia Hotel Apartamento"},"content":{"rendered":"<p><a href=\"http:\/\/www.portugalvia.com\/vp\/wp-content\/uploads\/2012\/01\/Antilia-Hotel-Apartamento2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-17768\" title=\"Antilia Hotel Apartamento\" src=\"http:\/\/www.portugalvia.com\/vp\/wp-content\/uploads\/2012\/01\/Antilia-Hotel-Apartamento2-300x207.jpg\" alt=\"\" width=\"300\" height=\"207\" srcset=\"https:\/\/portugalvia.com\/vp\/wp-content\/uploads\/2012\/01\/Antilia-Hotel-Apartamento2-300x207.jpg 300w, https:\/\/portugalvia.com\/vp\/wp-content\/uploads\/2012\/01\/Antilia-Hotel-Apartamento2-1024x708.jpg 1024w, https:\/\/portugalvia.com\/vp\/wp-content\/uploads\/2012\/01\/Antilia-Hotel-Apartamento2.jpg 1256w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Este Hotel, de 4 estrelas, integrado no Grupo Ciprotur, encontra-se centralmente localizado na cidade de Ponta Delgada, na ilha de S\u00e3o Miguel.<\/p>\n<p>A unidade hoteleira, disp\u00f5e de 48 apartamentos e 6 quartos. Todos os apartamentos disp\u00f5em de soalho em madeira, varanda, kitchenette totalmente equipada, sala de estar, casa de banho privativa, ar condicionado, aquecimento central, telefone com linha directa para o exterior, TV por cabo e acesso gratuito \u00e0 Internet.\u00a0 Os quartos disp\u00f5em de mini-bar e as mesmas facilidades dos apartamentos com excep\u00e7\u00e3o da sala de estar e kitchenette.<\/p>\n<p>O Hotel, disp\u00f5e de amplas \u00e1reas ajardinadas, zona infantil, uma piscina exterior para adultos e outra para crian\u00e7as, uma piscina interior aquecida, jacuzzi, sauna, banho turco, sol\u00e1rio, recinto coberto de squash, gin\u00e1sio, sal\u00e3o de jogos, sala de TV, biblioteca e uma sala preparada para a realiza\u00e7\u00e3o de\u00a0 reuni\u00f5es e de eventos at\u00e9 50 pessoas.<\/p>\n<p>Encontra-se igualmente dispon\u00edvel no Hotel, um restaurante e um bar com explanada, ambos com vista panor\u00e2mica e acesso ao deck da piscina, constituem a oferta de restaura\u00e7\u00e3o.\u00a0 No edif\u00edcio encontram-se dispon\u00edvel um cabeleireiro, um mini-mercado, multibanco e garagem privativa. Na cidade de Ponta Delgada, existem v\u00e1rias ofertas de espa\u00e7os culturais, de lazer e de divers\u00e3o, bem como espa\u00e7os verdes ajardinados.<\/p>\n<p>Como locais de interesse em Ponta Delgada, destacam-se a Igreja Matriz, o edif\u00edcio da Sede da Alf\u00e2ndega, os Conventos da Concei\u00e7\u00e3o (actual sede do governo regional dos A\u00e7ores), de Santo Andr\u00e9, do Carmo e de Nossa Senhora da Esperan\u00e7a, o antigo Col\u00e9gio dos Jesu\u00edtas, o Forte de S\u00e3o Br\u00e1s (tamb\u00e9m conhecido por Castelo de S\u00e3o Br\u00e1s), a Igreja de S\u00e3o Mateus e as Portas da Cidade.<\/p>\n<p><strong>Rua do Peru, 105 <\/strong><br \/>\n<strong>9500-311 Ponta Delgada <\/strong><br \/>\n<strong>S\u00e3o Miguel <\/strong><br \/>\n<strong>Telefone- (351) 296 206 000\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0<\/strong><br \/>\n<strong>Fax- (+351) 296 206 005\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0<\/strong><\/p>\n<p><span style=\"color: #008080;\"><strong><a href=\"http:\/\/aparthotel-antillia.com\/\"><span style=\"color: #008080;\">http:\/\/aparthotel-antillia.com<\/span><\/a><\/strong><\/span><\/p>\n<div>\n<script type='text\/javascript'>printBookingPanel('antillia-apartamentos.pt');<\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este Hotel, de 4 estrelas, integrado no Grupo Ciprotur, encontra-se centralmente localizado na cidade de Ponta Delgada, na ilha de S\u00e3o Miguel. A unidade hoteleira, disp\u00f5e de 48 apartamentos e 6 quartos. Todos os apartamentos disp\u00f5em de soalho em madeira, varanda, kitchenette totalmente equipada, sala de estar, casa de banho privativa, ar condicionado, aquecimento central, telefone com linha directa para o exterior, TV por cabo e acesso gratuito \u00e0 Internet.\u00a0 Os quartos disp\u00f5em de mini-bar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188,191],"tags":[],"class_list":["post-17464","post","type-post","status-publish","format-standard","hentry","category-acores","category-hoteis-acores"],"_links":{"self":[{"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/posts\/17464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/comments?post=17464"}],"version-history":[{"count":7,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/posts\/17464\/revisions"}],"predecessor-version":[{"id":17765,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/posts\/17464\/revisions\/17765"}],"wp:attachment":[{"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/media?parent=17464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/categories?post=17464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portugalvia.com\/vp\/wp-json\/wp\/v2\/tags?post=17464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}